{"id":70570,"count":1,"description":"","link":"https:\/\/greattelangaana.com\/english\/tag\/no-control-over-fuel-rates\/","name":"No control over fuel rates","slug":"no-control-over-fuel-rates","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/tags\/70570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/posts?tags=70570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}