{"id":66031,"count":1,"description":"","link":"https:\/\/greattelangaana.com\/english\/tag\/awe-movie-team-at-radio-mirchi-gallery\/","name":"Awe Movie Team At Radio Mirchi Gallery","slug":"awe-movie-team-at-radio-mirchi-gallery","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/tags\/66031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/posts?tags=66031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}