{"id":25450,"count":1,"description":"","link":"https:\/\/greattelangaana.com\/english\/tag\/congress-poll-manifesto\/","name":"Congress poll manifesto","slug":"congress-poll-manifesto","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/tags\/25450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/posts?tags=25450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}