{"id":111738,"count":8,"description":"","link":"https:\/\/greattelangaana.com\/english\/tag\/tomato-price\/","name":"tomato price","slug":"tomato-price","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/tags\/111738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/posts?tags=111738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}