{"id":101995,"count":1,"description":"","link":"https:\/\/greattelangaana.com\/english\/tag\/director-of-baahubali\/","name":"director of Baahubali","slug":"director-of-baahubali","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/tags\/101995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/greattelangaana.com\/english\/wp-json\/wp\/v2\/posts?tags=101995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}